{"id":223,"count":10,"description":"","link":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/","name":"Telemetria Elproma","slug":"telemetry-pl","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v24.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Telemetria Elproma Archives - Elproma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telemetria Elproma Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Elproma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/\",\"url\":\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/\",\"name\":\"Telemetria Elproma Archives - Elproma\",\"isPartOf\":{\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elpromaelectronics.com\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telemetria Elproma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#website\",\"url\":\"https:\/\/www.elpromaelectronics.com\/pl\/\",\"name\":\"Elproma\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elpromaelectronics.com\/pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#organization\",\"name\":\"Elproma Elektronika Sp. z o.o.\",\"url\":\"https:\/\/www.elpromaelectronics.com\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.elpromaelectronics.com\/wp-content\/uploads\/2021\/09\/Elproma_logo.jpg\",\"contentUrl\":\"https:\/\/www.elpromaelectronics.com\/wp-content\/uploads\/2021\/09\/Elproma_logo.jpg\",\"width\":1024,\"height\":229,\"caption\":\"Elproma Elektronika Sp. z o.o.\"},\"image\":{\"@id\":\"https:\/\/www.elpromaelectronics.com\/pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/elproma-electronics\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Telemetria Elproma Archives - Elproma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/","og_locale":"pl_PL","og_type":"article","og_title":"Telemetria Elproma Archives","og_url":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/","og_site_name":"Elproma","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/","url":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/","name":"Telemetria Elproma Archives - Elproma","isPartOf":{"@id":"https:\/\/www.elpromaelectronics.com\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elpromaelectronics.com\/pl\/category\/telemetry-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elpromaelectronics.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Telemetria Elproma"}]},{"@type":"WebSite","@id":"https:\/\/www.elpromaelectronics.com\/pl\/#website","url":"https:\/\/www.elpromaelectronics.com\/pl\/","name":"Elproma","description":"","publisher":{"@id":"https:\/\/www.elpromaelectronics.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elpromaelectronics.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.elpromaelectronics.com\/pl\/#organization","name":"Elproma Elektronika Sp. z o.o.","url":"https:\/\/www.elpromaelectronics.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.elpromaelectronics.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/www.elpromaelectronics.com\/wp-content\/uploads\/2021\/09\/Elproma_logo.jpg","contentUrl":"https:\/\/www.elpromaelectronics.com\/wp-content\/uploads\/2021\/09\/Elproma_logo.jpg","width":1024,"height":229,"caption":"Elproma Elektronika Sp. z o.o."},"image":{"@id":"https:\/\/www.elpromaelectronics.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/elproma-electronics\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.elpromaelectronics.com\/pl\/wp-json\/wp\/v2\/product_cat\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elpromaelectronics.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.elpromaelectronics.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.elpromaelectronics.com\/pl\/wp-json\/wp\/v2\/product?product_cat=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}